{"id":433,"date":"2017-07-19T08:57:14","date_gmt":"2017-07-19T08:57:14","guid":{"rendered":"http:\/\/www.nicdarkthemes.com\/themes\/hotel\/wp\/demo\/?page_id=433"},"modified":"2023-08-01T21:08:54","modified_gmt":"2023-08-01T19:08:54","slug":"wellness","status":"publish","type":"page","link":"https:\/\/cantalanotte.com\/en\/wellness\/","title":{"rendered":"Wellness"},"content":{"rendered":"<div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner vc_custom_1652800001877\"><div class=\"wpb_wrapper\"><div style=\"background-color:; height: 25px;\" class=\"nicdark_section  \"><\/div> <h2 style=\"color:#727475; padding:px; text-align:right; font-size:40px; line-height:50px; letter-spacing: px; font-weight:normal;\" class=\"  nd_options_text_align_center_responsive_important custom_text_mobile nd_options_first_font \">Breathe in the essence of the oldest Apulia, in luxury in complete relaxation.<\/h2> <\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div style=\"background-color:; height: 40px;\" class=\"nicdark_section  \"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element  nd_options_text_align_center_responsive\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Immerse yourself in the infinity pool and you will suddenly feel as if you are swimming suspended in a vacuum. A large panoramic solarium surrounded by olive trees dominates the valley<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div style=\"background-color:; height: 40px;\" class=\"nicdark_section none-mobile \"><\/div>\n\t<div class=\"wpb_text_column wpb_content_element  nd_options_text_align_center_responsive\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"R3Gmyc qwU8Me\">\n<div class=\"WUFI9b\" data-tab-id=\"2\">\n<div class=\"hWX4r\">\n<div class=\"z38b6\" aria-live=\"polite\">\n<div class=\"GDhqjd\" tabindex=\"-1\" data-sender-id=\"spaces\/XRAU6MeXOf8B\/devices\/777bb07a-ade8-4890-83d4-2edce9884c32\" data-sender-name=\"Antonio J. Lupo\" data-timestamp=\"1652713201000\" data-formatted-timestamp=\"17:00\">\n<div class=\"Zmm6We\">\n<div class=\"oIy2qc\" data-message-text=\"Immergiti nella piscina sfioro e all\u2019improvviso ti sembrer\u00e0 di nuotare sospeso nel vuoto. Un ampio solarium panoramico circondato da ulivi domina la valle con una vista mozzafiato. Nelle giornate pi\u00f9 fredde potrai trovare il massimo relax abbandonandoti nella sauna finlandese panoramica. \">with a breathtaking view. On colder days, you can find ultimate relaxation by indulging in the panoramic Finnish sauna.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"UnvNgf Sdwpn P9KVBf\">\n<div class=\"lefKC\">\n<div class=\"gSlHI\">\n<div class=\"Cpvy4b V7iHrd\">\n<div class=\"Qp8KI\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1492510780167\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div style=\"background-color:; height: 10px;\" class=\"nicdark_section  \"><\/div>\n\n  <!--START team-->\n  <div class=\" nd_options_team_component_l5 nd_options_section nd_options_box_sizing_border_box  \">    \n    <div class=\"nd_options_section nd_options_position_relative\">\n\n      <img alt=\"\" class=\"nd_options_section\" src=\"https:\/\/cantalanotte.com\/wp-content\/uploads\/2022\/05\/piscina-1024x839.jpg\">\n\n      <div class=\"nd_options_bg_greydark_alpha_gradient_3 nd_options_position_absolute nd_options_left_0 nd_options_height_100_percentage nd_options_width_100_percentage nd_options_box_sizing_border_box\">\n        <div class=\"nd_options_position_absolute nd_options_bottom_30 nd_options_width_100_percentage nd_options_padding_botttom_0 nd_options_padding_50 nd_options_box_sizing_border_box nd_options_text_align_center\">\n          <h3 class=\"nd_options_color_white\">INFINITY POOL<\/h3>\n          <div class=\"nd_options_section nd_options_height_10\"><\/div>\n          <h6 class=\"nd_options_color_white\"><strong>WITH CASCADE<\/strong><\/h6>\n        <\/div>\n      <\/div>\n\n    <\/div>\n  <\/div>\n  <!--END team-->\n<div style=\"background-color:; height: 10px;\" class=\"nicdark_section  \"><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div style=\"background-color:; height: 10px;\" class=\"nicdark_section  \"><\/div>\n\n  <!--START team-->\n  <div class=\" nd_options_team_component_l5 nd_options_section nd_options_box_sizing_border_box  \">    \n    <div class=\"nd_options_section nd_options_position_relative\">\n\n      <img alt=\"\" class=\"nd_options_section\" src=\"https:\/\/cantalanotte.com\/wp-content\/uploads\/2022\/05\/sauna-1024x839.jpeg\">\n\n      <div class=\"nd_options_bg_greydark_alpha_gradient_3 nd_options_position_absolute nd_options_left_0 nd_options_height_100_percentage nd_options_width_100_percentage nd_options_box_sizing_border_box\">\n        <div class=\"nd_options_position_absolute nd_options_bottom_30 nd_options_width_100_percentage nd_options_padding_botttom_0 nd_options_padding_50 nd_options_box_sizing_border_box nd_options_text_align_center\">\n          <h3 class=\"nd_options_color_white\">FINNISH SAUNA<\/h3>\n          <div class=\"nd_options_section nd_options_height_10\"><\/div>\n          <h6 class=\"nd_options_color_white\"><strong>WITH PANORAMIC VIEW<\/strong><\/h6>\n        <\/div>\n      <\/div>\n\n    <\/div>\n  <\/div>\n  <!--END team-->\n<div style=\"background-color:; height: 10px;\" class=\"nicdark_section  \"><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div style=\"background-color:; height: 10px;\" class=\"nicdark_section  \"><\/div>\n\n  <!--START team-->\n  <div class=\" nd_options_team_component_l5 nd_options_section nd_options_box_sizing_border_box  \">    \n    <div class=\"nd_options_section nd_options_position_relative\">\n\n      <img alt=\"\" class=\"nd_options_section\" src=\"https:\/\/cantalanotte.com\/wp-content\/uploads\/2022\/05\/solarium-1024x839.jpeg\">\n\n      <div class=\"nd_options_bg_greydark_alpha_gradient_3 nd_options_position_absolute nd_options_left_0 nd_options_height_100_percentage nd_options_width_100_percentage nd_options_box_sizing_border_box\">\n        <div class=\"nd_options_position_absolute nd_options_bottom_30 nd_options_width_100_percentage nd_options_padding_botttom_0 nd_options_padding_50 nd_options_box_sizing_border_box nd_options_text_align_center\">\n          <h3 class=\"nd_options_color_white\">SOLARIUM<\/h3>\n          <div class=\"nd_options_section nd_options_height_10\"><\/div>\n          <h6 class=\"nd_options_color_white\"><strong>SURROUNDED BY OLIVE TREES<\/strong><\/h6>\n        <\/div>\n      <\/div>\n\n    <\/div>\n  <\/div>\n  <!--END team-->\n<div style=\"background-color:; height: 10px;\" class=\"nicdark_section  \"><\/div><\/div><\/div><\/div><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" data-vc-parallax=\"1.5\" data-vc-parallax-image=\"\" class=\"vc_row wpb_row vc_row-fluid nd_options_vc_parallax_filter_2_2 vc_custom_1652892380334 vc_row-has-fill vc_general vc_parallax vc_parallax-content-moving\"><div class=\"no-padding-m wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\n\n    <div class=\"nd_options_section nd_options_position_relative nd_options_service_about_l5\">\n        <img alt=\"\" class=\"nd_options_position_absolute nd_options_left_0\" width=\"55\" src=\"\">\n        <div class=\"nd_options_section nd_options_padding_left_80 nd_options_box_sizing_border_box\">\n            <h1 class=\"nd_options_font_size_40 nd_options_line_height_50\" style=\"color:#ffffff;\"><strong>All the comfort of the village available to our guests.<\/strong><\/h1>\n        <\/div>\n    <\/div>\n\n\n  <div style=\"background-color:; height: 70px;\" class=\"nicdark_section  \"><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner vc_custom_1469630269458\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img class=\"vc_single_image-img \" src=\"https:\/\/cantalanotte.com\/wp-content\/uploads\/2022\/05\/teli-da-mare-80x80.png\" width=\"80\" height=\"80\" alt=\"teli da mare\" title=\"teli da mare\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n <p style=\"color:#ffffff; padding:px; text-align:center; font-size:15px; line-height:30px; letter-spacing: 2px; font-weight:lighter;\" class=\"   nd_options_second_font \">Bath towels<\/p> <\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner vc_custom_1469630276028\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img class=\"vc_single_image-img \" src=\"https:\/\/cantalanotte.com\/wp-content\/uploads\/2022\/05\/accessori-80x80.png\" width=\"80\" height=\"80\" alt=\"accessori\" title=\"accessori\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n <p style=\"color:#ffffff; padding:px; text-align:center; font-size:15px; line-height:30px; letter-spacing: 2px; font-weight:lighter;\" class=\"   nd_options_second_font \">Small cosmetic products<\/p> <\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner vc_custom_1469630283566\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img class=\"vc_single_image-img \" src=\"https:\/\/cantalanotte.com\/wp-content\/uploads\/2022\/05\/bagno-80x80.png\" width=\"80\" height=\"80\" alt=\"bagno\" title=\"bagno\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n <p style=\"color:#ffffff; padding:px; text-align:center; font-size:15px; line-height:30px; letter-spacing: 2px; font-weight:lighter;\" class=\"   nd_options_second_font \">Bathroom accessories<\/p> <\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner vc_custom_1469630289168\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img class=\"vc_single_image-img \" src=\"https:\/\/cantalanotte.com\/wp-content\/uploads\/2022\/05\/lettini-80x80.png\" width=\"80\" height=\"80\" alt=\"lettini\" title=\"lettini\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n <p style=\"color:#ffffff; padding:px; text-align:center; font-size:15px; line-height:30px; letter-spacing: 2px; font-weight:lighter;\" class=\"   nd_options_second_font \">Comfortable loungers<\/p> <\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid nd_options_vc_parallax_filter_2_2 vc_custom_1690916872802 vc_row-o-content-top vc_row-flex\"><div class=\"no-padding-m wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"> <h2 style=\"color:#727475; padding:px; text-align:center; font-size:40px; line-height:50px; letter-spacing: px; font-weight:normal;\" class=\"  nd_options_text_align_center_responsive_important custom_text_mobile nd_options_first_font \">Wellness Planimetry<\/h2> <div style=\"background-color:; height: 50px;\" class=\"nicdark_section  \"><\/div>\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a class=\"\" data-lightbox=\"lightbox[rel-433-2585838429]\" href=\"https:\/\/cantalanotte.com\/wp-content\/uploads\/2023\/08\/Cantalanotte_Planimetry__Spa.png\" target=\"_self\" class=\"vc_single_image-wrapper vc_box_rounded  vc_box_border_grey\"><img width=\"893\" height=\"631\" src=\"https:\/\/cantalanotte.com\/wp-content\/uploads\/2023\/08\/Cantalanotte_Planimetry__Spa.png\" class=\"vc_single_image-img attachment-large\" alt=\"\" decoding=\"async\" loading=\"lazy\" title=\"Cantalanotte_Planimetry__Spa\" srcset=\"https:\/\/cantalanotte.com\/wp-content\/uploads\/2023\/08\/Cantalanotte_Planimetry__Spa.png 893w, https:\/\/cantalanotte.com\/wp-content\/uploads\/2023\/08\/Cantalanotte_Planimetry__Spa-300x212.png 300w, https:\/\/cantalanotte.com\/wp-content\/uploads\/2023\/08\/Cantalanotte_Planimetry__Spa-768x543.png 768w, https:\/\/cantalanotte.com\/wp-content\/uploads\/2023\/08\/Cantalanotte_Planimetry__Spa-18x12.png 18w\" sizes=\"(max-width: 893px) 100vw, 893px\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner vc_custom_1652866223465\"><div class=\"wpb_wrapper\">\n\t\t\t<!-- START Gallery REVOLUTION SLIDER 6.5.21 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_6_1_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:#f9f9f9;padding:0;margin:0px auto;margin-top:0;margin-bottom:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_6_1\" style=\"\" data-version=\"6.5.21\">\n\t\t\t\t\t<rs-slides>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-15\" data-title=\"Piscina a sfioro\" data-thumb=\"\/\/cantalanotte.com\/wp-content\/uploads\/2022\/05\/wellness1-768x512-150x100.jpg\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img src=\"\/\/cantalanotte.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" title=\"wellness1\" width=\"768\" height=\"512\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/cantalanotte.com\/wp-content\/uploads\/2022\/05\/wellness1-768x512.jpg\" data-bg=\"f:contain;\" data-no-retina>\n<!---->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-60\" data-title=\"Family Room\" data-thumb=\"\/\/cantalanotte.com\/wp-content\/uploads\/2022\/05\/wellness2-768x512-150x100.jpg\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img src=\"\/\/cantalanotte.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" title=\"wellness2\" width=\"768\" height=\"512\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/cantalanotte.com\/wp-content\/uploads\/2022\/05\/wellness2-768x512.jpg\" data-bg=\"f:contain;\" data-no-retina>\n<!---->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-62\" data-title=\"Family Room\" data-thumb=\"\/\/cantalanotte.com\/wp-content\/uploads\/2022\/05\/wellness3-768x512-150x100.jpg\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img src=\"\/\/cantalanotte.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" title=\"wellness3\" width=\"768\" height=\"512\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/cantalanotte.com\/wp-content\/uploads\/2022\/05\/wellness3-768x512.jpg\" data-bg=\"f:contain;\" data-no-retina>\n<!---->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-63\" data-title=\"Family Room\" data-thumb=\"\/\/cantalanotte.com\/wp-content\/uploads\/2022\/05\/wellness4-768x512-150x100.jpg\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img src=\"\/\/cantalanotte.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" title=\"wellness4\" width=\"768\" height=\"512\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/cantalanotte.com\/wp-content\/uploads\/2022\/05\/wellness4-768x512.jpg\" data-bg=\"f:contain;\" data-no-retina>\n<!---->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-64\" data-title=\"Family Room\" data-thumb=\"\/\/cantalanotte.com\/wp-content\/uploads\/2022\/05\/solarium-768x629-150x100.jpeg\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img src=\"\/\/cantalanotte.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" title=\"solarium\" width=\"768\" height=\"629\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/cantalanotte.com\/wp-content\/uploads\/2022\/05\/solarium-768x629.jpeg\" data-bg=\"f:contain;\" data-no-retina>\n<!---->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script>\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_6_1',rl:[1240,1024,778,480],el:[525],gw:[600],gh:[525],type:'carousel',justify:'',layout:'fullwidth',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider61\"]!==undefined) {window.RS_MODULES.modules[\"revslider61\"].once = false;window.revapi6 = undefined;if (window.RS_MODULES.checkMinimal!==undefined) window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n<\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"Breathe in the essence of the oldest Apulia, in luxury in complete relaxation. Immerse yourself in the infinity pool and you will suddenly feel as if you are swimming suspended in a vacuum. A large panoramic solarium surrounded by olive trees dominates the valley with a breathtaking view. On colder days, you can find ultimate [...]","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/cantalanotte.com\/en\/wp-json\/wp\/v2\/pages\/433"}],"collection":[{"href":"https:\/\/cantalanotte.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cantalanotte.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cantalanotte.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cantalanotte.com\/en\/wp-json\/wp\/v2\/comments?post=433"}],"version-history":[{"count":104,"href":"https:\/\/cantalanotte.com\/en\/wp-json\/wp\/v2\/pages\/433\/revisions"}],"predecessor-version":[{"id":2364,"href":"https:\/\/cantalanotte.com\/en\/wp-json\/wp\/v2\/pages\/433\/revisions\/2364"}],"wp:attachment":[{"href":"https:\/\/cantalanotte.com\/en\/wp-json\/wp\/v2\/media?parent=433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}